{"id":10458,"date":"2021-12-15T11:33:13","date_gmt":"2021-12-15T17:33:13","guid":{"rendered":"https:\/\/elsalvadorllantas.com\/?post_type=product&#038;p=10458"},"modified":"2026-04-13T23:33:00","modified_gmt":"2026-04-14T05:33:00","slug":"toyo-265-65-r17-opat3-6pr-116t","status":"publish","type":"product","link":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/","title":{"rendered":"Toyo 265\/65 R17 OPAT3 6PR 116T"},"content":{"rendered":"<table style=\"height: 67px;\" border=\"2\" width=\"777\">\n<tbody>\n<tr style=\"text-align: center;\">\n<td>\u00cdndice de Velocidad<\/td>\n<td>\u00cdndice de Carga<\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td>T<\/td>\n<td>116<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\t\t<div data-elementor-type=\"page\" data-elementor-id=\"12773\" class=\"elementor elementor-12773\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe26f44 elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"fe26f44\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b7ca9ec\" data-id=\"5b7ca9ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-103ffca8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"103ffca8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-628fd667\" data-id=\"628fd667\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-269ca1f7 elementor-widget elementor-widget-image\" data-id=\"269ca1f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"51\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2018\/04\/Logo-Toyo-Tires-menu.png\" class=\"attachment-large size-large wp-image-9765\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2018\/04\/Logo-Toyo-Tires-menu.png 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2018\/04\/Logo-Toyo-Tires-menu-64x11.png 64w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56ebd6f6 elementor-widget elementor-widget-image\" data-id=\"56ebd6f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"89\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-1024x89.jpg\" class=\"attachment-large size-large wp-image-10476\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-1024x89.jpg 1024w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-300x26.jpg 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-768x67.jpg 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-1536x134.jpg 1536w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-600x52.jpg 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-64x6.jpg 64w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3.jpg 1633w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fb1a23a elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fb1a23a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7bc6dde3\" data-id=\"7bc6dde3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-243ecb48 elementor-widget elementor-widget-heading\" data-id=\"243ecb48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OPAT3 - Open Country A\/T III<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dda7c57 elementor-widget elementor-widget-text-editor\" data-id=\"1dda7c57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La llanta Toyo Open Country A\/T III, para uso Todo-Terreno cuenta<br \/>con 45 diferentes medidas para uso en veh\u00edculos familiares,<br \/>recreacionales y utilitarios.<br \/>Open Country A\/T III es ahora la llanta con la mas amplia gama de<br \/>medidas, rangos de carga e \u00edndices de velocidad para todas las<br \/>necesidades el mercado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bf96a08 elementor-widget elementor-widget-price-list\" data-id=\"6bf96a08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"price-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<ul class=\"elementor-price-list\">\n\n\t\t\t\t\t\t\t\t\t<li><a class=\"elementor-price-list-item\" href=\"#\">\t\t\t\t\n\t\t\t\t<div class=\"elementor-price-list-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-price-list-header\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-title\">\n\t\t\t\t\t\t\tTotal Dimensiones\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-separator\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-price\">45 tama\u00f1os P\/Euro y LT-metric<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a><\/li>\t\t\t\t\t\t\t\t\t\t\t\t<li><a class=\"elementor-price-list-item\" href=\"#\">\t\t\t\t\n\t\t\t\t<div class=\"elementor-price-list-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-price-list-header\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-title\">\n\t\t\t\t\t\t\tDi\u00e1metros del rin\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-separator\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-price\">15\u201d \u2013 22\u201d<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a><\/li>\t\t\t\t\t\t\t\t\t\t\t\t<li><a class=\"elementor-price-list-item\" href=\"#\">\t\t\t\t\n\t\t\t\t<div class=\"elementor-price-list-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-price-list-header\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-title\">\n\t\t\t\t\t\t\tS\u00edmbolos de Velocidad\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-separator\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-price\">Q, R, S, T, H<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a><\/li>\t\t\t\t\t\t\t\t\t\t\t\t<li><a class=\"elementor-price-list-item\" href=\"#\">\t\t\t\t\n\t\t\t\t<div class=\"elementor-price-list-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-price-list-header\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-title\">\n\t\t\t\t\t\t\tAplicaci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-separator\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-list-price\">Pick Up, SUV & CUV<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a><\/li>\t\t\t\t\t\n\t\t<\/ul>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30abb250\" data-id=\"30abb250\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4366dfc4 elementor-widget elementor-widget-image\" data-id=\"4366dfc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"778\" height=\"1004\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-33333333-1.png\" class=\"attachment-large size-large wp-image-11260\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-33333333-1.png 778w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-33333333-1-232x300.png 232w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-33333333-1-768x991.png 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-33333333-1-600x774.png 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-33333333-1-64x83.png 64w\" sizes=\"(max-width: 778px) 100vw, 778px\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14429694 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"14429694\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1ea83759\" data-id=\"1ea83759\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-756efd7d elementor-widget elementor-widget-spacer\" data-id=\"756efd7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7afe7687\" data-id=\"7afe7687\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-575e9705 elementor-widget elementor-widget-heading\" data-id=\"575e9705\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Para uso en veh\u00edculos Familiares<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e3499d7 elementor-widget elementor-widget-heading\" data-id=\"4e3499d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OPAT3 - Veh\u00edculos Familiares<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-679ebd05 elementor-widget elementor-widget-text-editor\" data-id=\"679ebd05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Las llantas Toyo POAT3 &#8211; Open Country A\/T III (P=Passenger) pueden usarse en veh\u00edculos familiares compactos preferidos por conductores tipo entusiastas, adultos j\u00f3venes que disfrutan de la naturaleza y pasan tiempo en familia al aire libre.<br \/>Regularmente eligen veh\u00edculos con especificaciones AWD o 4WD para poder accesar a cualquier terreno, incluso usar en la ciudad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c7b8305 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-reverse-mobile elementor-section-height-default\" data-id=\"4c7b8305\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7dead5f9\" data-id=\"7dead5f9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48e43fdd elementor-widget elementor-widget-heading\" data-id=\"48e43fdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Para uso en veh\u00edculos de Turismo<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52799a70 elementor-widget elementor-widget-heading\" data-id=\"52799a70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OPAT3 - Pick Up y SUV<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ff8995d elementor-widget elementor-widget-text-editor\" data-id=\"3ff8995d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">En ocasiones este perfil de cliente decide comprar veh\u00edculos con uso mixto de carga y pasajeros y\/o veh\u00edculos familiares con cajuela amplia para poder usar en vacaciones o paseos de fin de semana en<br \/>traslados en carretera y fuera de carretera.<br \/>La apariencia y equipamiento del veh\u00edculo es muy importante para estos clientes por eso buscan llantas Todo-Terreno desde el Equipo Original o incluso llegan a reemplazar las llantas originales al momento de la compra. Para esto, las llantas Toyo POAT3 &#8211; Open Country A\/T III son ideales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-57929742\" data-id=\"57929742\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1520d77d elementor-widget elementor-widget-spacer\" data-id=\"1520d77d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f355b3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f355b3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50d71bed\" data-id=\"50d71bed\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4543d97c elementor-widget elementor-widget-spacer\" data-id=\"4543d97c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b07377 elementor-widget elementor-widget-heading\" data-id=\"77b07377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">OPAT3 - Para uso en veh\u00edculos de carga y\/o utilitarios<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45228183 elementor-widget elementor-widget-text-editor\" data-id=\"45228183\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las llantas Toyo OPAT3 Open Country A\/T III LT (Light Truck) son <span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">la recomendaci\u00f3n ideal para aquellos personas que\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">buscan una llanta con alta resistencia y capacidad de\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">carga para ser montada en veh\u00edculos ADW-4WD que\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">regularmente son usados para actividades de recreaci\u00f3n,\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">como pesca, playa, motocross, turismo en monta\u00f1a, etc..,\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">o actividades de trabajo como la ganader\u00eda y\/o\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">agricultura.<\/span><\/p><p>En muchas ocasiones, estos veh\u00edculos de gran potencia de motor y carga, son usados para remolcar lanchas, motocicletas, caballos o casas rodantes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46271478 elementor-widget elementor-widget-image\" data-id=\"46271478\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"257\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-11-1.png\" class=\"attachment-large size-large wp-image-11263\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-11-1.png 900w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-11-1-300x86.png 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-11-1-768x219.png 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-11-1-600x171.png 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-11-1-64x18.png 64w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c0049d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c0049d3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7bdaf4c2\" data-id=\"7bdaf4c2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75c73bc4 elementor-widget elementor-widget-heading\" data-id=\"75c73bc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">OPAT3 - Equipo Original<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48bd4700 elementor-widget elementor-widget-text-editor\" data-id=\"48bd4700\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando el equipamiento original de algunos veh\u00edculos incluyen llantas Todo-Terreno como parte de su especificaci\u00f3n de f\u00e1brica,<br \/>hay una muy alta posibilidad que en el remplazo se decida por una llanta de la misma aplicaci\u00f3n, por tal motivo es imprescindible<br \/>identificar \u00e9stos casos para proponer la llanta Toyo OPAT3 &#8211; Open Country A\/T III ya que es la mejor opci\u00f3n en el mercado por su seguridad y desempe\u00f1o en condiciones uso mixto, y sobre todo mantienen el nivel de equipo del veh\u00edculo con llantas de alta calidad y apreciaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45651477 elementor-widget elementor-widget-image\" data-id=\"45651477\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"327\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-16-1-1024x327.png\" class=\"attachment-large size-large wp-image-11264\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-16-1-1024x327.png 1024w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-16-1-300x96.png 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-16-1-768x245.png 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-16-1-600x192.png 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-16-1-64x20.png 64w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-16-1.png 1033w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bc20a25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bc20a25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28cc0898\" data-id=\"28cc0898\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-231bdc88 elementor-widget elementor-widget-heading\" data-id=\"231bdc88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OPAT3 - Caracter\u00edsticas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa90099 elementor-widget elementor-widget-text-editor\" data-id=\"2fa90099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La nueva llanta Toyo Opat3 Open Country A \/ T III ofrece excelente tracci\u00f3n en condiciones de uso Todo-Terreno y una conducci\u00f3n silenciosa y segura. Estas prestaciones se logran por su nuevo dise\u00f1o de banda de rodamiento y su mezcla de compuestos de hule, en conjunto dise\u00f1ados para veh\u00edculos que requieren usarse en condiciones mixtas.<\/p><p>Open Opat3 Country A \/ T III est\u00e1 dise\u00f1ada para salir y regresar a casa, independientemente de las condiciones de terreno o clima que puedan presentarse. Es sin duda la mejor opci\u00f3n para tu veh\u00edculo por su rendimiento, seguridad y estabilidad cuando se usa en superficies secas o mojadas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-435cea21 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"435cea21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-62c9bace\" data-id=\"62c9bace\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6031f93b elementor-widget elementor-widget-icon-box\" data-id=\"6031f93b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBloques alternados en el hombro\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIncrementan la capacidad de tracci\u00f3n en condiciones fuera de carretera en situaciones de superficies arenosas o lodosas.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18eca670 elementor-widget elementor-widget-icon-box\" data-id=\"18eca670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBanda de Rodamiento con bloques centrales.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDise\u00f1o de huella de contacto especialmente\npensada para proporcionar mucha tracci\u00f3n y\nm\u00e1xima estabilidad gracias a la disposici\u00f3n y\ntama\u00f1o de sus bloques creando una mayor\nhuella de contacto.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-733cb608\" data-id=\"733cb608\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b8106be elementor-widget elementor-widget-hotspot\" data-id=\"4b8106be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;731c40e&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Bloques alternados en el hombro&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position_mobile&quot;:&quot;left&quot;,&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:140,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;yes&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Banda de Rodamiento con&lt;br \\\/&gt;bloques centrales.&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:24,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;11af284&quot;,&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position_mobile&quot;:&quot;bottom&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;&quot;},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Canales circunferenciales.&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:74,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:41,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;1ee0948&quot;,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position_mobile&quot;:&quot;right&quot;,&quot;hotspot_tooltip_text_wrap&quot;:&quot;yes&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Canales Trasversales.&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:48,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:64,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;ca32ad8&quot;,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position_mobile&quot;:&quot;top&quot;,&quot;hotspot_tooltip_text_wrap&quot;:&quot;yes&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}],&quot;tooltip_position_mobile&quot;:&quot;left&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;,&quot;tooltip_position&quot;:&quot;top&quot;,&quot;tooltip_trigger&quot;:&quot;click&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-in-out&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"890\" height=\"1024\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/opat3Caracteristicas-1-890x1024.png\" class=\"attachment-large size-large wp-image-11265\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/opat3Caracteristicas-1-890x1024.png 890w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/opat3Caracteristicas-1-261x300.png 261w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/opat3Caracteristicas-1-768x883.png 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/opat3Caracteristicas-1-600x690.png 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/opat3Caracteristicas-1-64x74.png 64w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/opat3Caracteristicas-1.png 900w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/>\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-731c40e  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Bloques alternados en el hombro<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-11af284  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Banda de Rodamiento con<br \/>bloques centrales.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-1ee0948  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Canales circunferenciales.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-ca32ad8  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Canales Trasversales.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7779e377\" data-id=\"7779e377\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60a60eca elementor-widget elementor-widget-icon-box\" data-id=\"60a60eca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCanales circunferenciales.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAmplios canales en forma de zig-zag\nfavorecen la evacuaci\u00f3n del agua\nasegurando una conducci\u00f3n segura en\ncondiciones con lluvia.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d07023e elementor-widget elementor-widget-icon-box\" data-id=\"2d07023e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCanales Trasversales.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDise\u00f1o alternado de canales trasversales\nque favorecen la evacuaci\u00f3n de lodo, arena\no nieve asegurando una mayor tracci\u00f3n\nmientras ofrece una apariencia moderna y\nagresiva.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29d4ab58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29d4ab58\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-691baf57\" data-id=\"691baf57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cfc1b3c elementor-widget elementor-widget-heading\" data-id=\"2cfc1b3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OPAT3 - Construcci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0a11c2 elementor-widget elementor-widget-text-editor\" data-id=\"4e0a11c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entre la construcci\u00f3n de la \u00a0llanta Toyo Opat3 Open Country A \/ T III encontramos bloques del hombro alternados, uno con forma de canal o concavidad y otro en 90 grados que incrementan la capacidad de tracci\u00f3n lateral. Bloques del hombro y del costado con ribetes dispuestos en un \u00e1ngulo que ayuda a tener m\u00e1xima tracci\u00f3n en los costados .Bloques en el costado dispuestos en la zona de mayor flexi\u00f3n<br \/>generando m\u00e1xima protecci\u00f3n en los costados por impactos por piedras, guarniciones, o cualquier otro elemento propio de las condiciones fuera carretera.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-615e1273 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"615e1273\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6eb6e673\" data-id=\"6eb6e673\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ac75120 elementor-widget elementor-widget-hotspot\" data-id=\"2ac75120\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;731c40e&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Dos cinturones con tecnolog\\u00eda \\&quot;Spiral Wound\\&quot;&lt;br \\\/&gt;exclusiva de Toyo Tires que aseguran mayor&lt;br \\\/&gt;estabilidad y un desgaste uniforme en la banda&lt;br \\\/&gt;de rodamiento por su construcci\\u00f3n con&lt;br \\\/&gt;tecnolog\\u00eda A.T.O.M que dispone los cables&lt;br \\\/&gt;circunferencialmente y con un punto de uni\\u00f3n&lt;br \\\/&gt;muy peque\\u00f1o.&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:37,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position_tablet&quot;:&quot;left&quot;,&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:364,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;yes&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Dos cinturones de acero de alta resistencia que&lt;br \\\/&gt;protegen en todo la ancho de la banda rodamiento&lt;br \\\/&gt;para reducir los da\\u00f1o por piedras, vidrio y&lt;br \\\/&gt;penetraciones caracter\\u00edsticas de las condiciones&lt;br \\\/&gt;de uso mixto.&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:46,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;11af284&quot;,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:273,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;yes&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Carcasa radial de poli\\u00e9ster asegurando&lt;br \\\/&gt;flexibilidad y una conducci\\u00f3n agradable&lt;br \\\/&gt;manteniendo alta seguridad.&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:49,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:56,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;1ee0948&quot;,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:215,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;yes&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Haz de ceja construido sin uniones gracias&lt;br \\\/&gt;a la tecnolog\\u00eda exclusiva de Toyo Tires.&lt;br \\\/&gt;Asegurando un firme ensamble al rin y&lt;br \\\/&gt;m\\u00e1xima seguridad.&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:63,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:84,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;ca32ad8&quot;,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position_tablet&quot;:&quot;bottom&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;&quot;},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Protector de RIn, ribete circunferencial en&lt;br \\\/&gt;la en el perimetro de asentamiento del rin&lt;br \\\/&gt;que por su exposici\\u00f3n protege al rin de&lt;br \\\/&gt;aluminio sobre impactos laterales en la&lt;br \\\/&gt;zona.&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:79,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:52,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;240f431&quot;,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position_tablet&quot;:&quot;right&quot;,&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:257,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;yes&quot;,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}],&quot;tooltip_position&quot;:&quot;left&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;,&quot;tooltip_trigger&quot;:&quot;click&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-in-out&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"686\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Sin-titulo-1-1.png\" class=\"attachment-full size-full wp-image-10554\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Sin-titulo-1-1.png 1000w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Sin-titulo-1-1-300x206.png 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Sin-titulo-1-1-768x527.png 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Sin-titulo-1-1-600x412.png 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Sin-titulo-1-1-64x44.png 64w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-731c40e  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Dos cinturones con tecnolog\u00eda \"Spiral Wound\"<br \/>exclusiva de Toyo Tires que aseguran mayor<br \/>estabilidad y un desgaste uniforme en la banda<br \/>de rodamiento por su construcci\u00f3n con<br \/>tecnolog\u00eda A.T.O.M que dispone los cables<br \/>circunferencialmente y con un punto de uni\u00f3n<br \/>muy peque\u00f1o.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-11af284  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Dos cinturones de acero de alta resistencia que<br \/>protegen en todo la ancho de la banda rodamiento<br \/>para reducir los da\u00f1o por piedras, vidrio y<br \/>penetraciones caracter\u00edsticas de las condiciones<br \/>de uso mixto.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-1ee0948  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Carcasa radial de poli\u00e9ster asegurando<br \/>flexibilidad y una conducci\u00f3n agradable<br \/>manteniendo alta seguridad.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-ca32ad8  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Haz de ceja construido sin uniones gracias<br \/>a la tecnolog\u00eda exclusiva de Toyo Tires.<br \/>Asegurando un firme ensamble al rin y<br \/>m\u00e1xima seguridad.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-240f431  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p>Protector de RIn, ribete circunferencial en<br \/>la en el perimetro de asentamiento del rin<br \/>que por su exposici\u00f3n protege al rin de<br \/>aluminio sobre impactos laterales en la<br \/>zona.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c0dfbed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c0dfbed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b5c607\" data-id=\"5b5c607\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5431c9f3 elementor-widget elementor-widget-heading\" data-id=\"5431c9f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Dise\u00f1o agresivo de Costado y hombros<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fc9fe25 elementor-widget elementor-widget-text-editor\" data-id=\"1fc9fe25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Su nuevo dise\u00f1o de hombro y pared lateral m\u00e1s agresivo, el alternado de\u00a0 loques con hombros festoneados proporcionan tracci\u00f3n adicional en condiciones todo-terreno. Las asas del hombro se envuelven alrededor de la pared lateral del neum\u00e1tico,\u00a0proporcionando una superficie de tracci\u00f3n adicional. Este espesor adicional proporciona durabilidad, resistencia al moret\u00f3n y a la punci\u00f3n.<br \/>Protector de Rin Ribete circunferencial en la zona de asentamiento del rin que por su exposici\u00f3n recibe los impactos laterales propios de las condiciones de uso mixto protegiendo al rin de aluminio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3567343e\" data-id=\"3567343e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39324fe9 elementor-widget elementor-widget-image\" data-id=\"39324fe9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"744\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/NewDiseno-1.png\" class=\"attachment-large size-large wp-image-11266\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/NewDiseno-1.png 900w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/NewDiseno-1-300x248.png 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/NewDiseno-1-768x635.png 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/NewDiseno-1-600x496.png 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/NewDiseno-1-64x53.png 64w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f2c6f2 elementor-widget elementor-widget-heading\" data-id=\"75f2c6f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Primer producto con nuevo dise\u00f1o de costado\ncon el uso de marca \u201cToyo Tires\u201d.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c8661f elementor-widget elementor-widget-image\" data-id=\"4c8661f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"435\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-30-1.png\" class=\"attachment-large size-large wp-image-11268\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-30-1.png 900w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-30-1-300x145.png 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-30-1-768x371.png 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-30-1-600x290.png 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-30-1-64x31.png 64w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31705174 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31705174\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e641ef\" data-id=\"9e641ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-670e5f21 elementor-widget elementor-widget-heading\" data-id=\"670e5f21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OPAT3 - Opciones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fef087b elementor-widget elementor-widget-text-editor\" data-id=\"2fef087b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La llanta Toyo Todo-Terreno Open Country A \/ T III es la mejor opci\u00f3n para veh\u00edculos familiares, recreacionales o utilitarios por su estabilidad, duraci\u00f3n y m\u00e1xima<br \/>tracci\u00f3n ofreciendo una conducci\u00f3n segura y silenciosa. Su completamente nuevo dise\u00f1o en banda de rodamiento y costado, as\u00ed como la nueva composici\u00f3n<br \/>de mezcla de hules que junto con la alta tecnolog\u00eda de producci\u00f3n japonesa exclusiva de Toyo Tires es sin duda la mejor opci\u00f3n para quienes buscan un neum\u00e1tico Todo-Terreno. Open Country A \/ T III cuenta con la m\u00e1s amplia gama de medidas, rangos de carga e \u00edndices de velocidad del mercado, para atender cualquier necesidad del segmento:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-23c46c33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23c46c33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-130ccbe1\" data-id=\"130ccbe1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ab2ac94 elementor-widget elementor-widget-icon-box\" data-id=\"5ab2ac94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNomenclatura P Nomenclatura LT\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPasajeros (Veh\u00edculos familiares y\/o recreacionales) ofrece una conducci\u00f3n Veh\u00edculos utilitarios o de carga, ofrece\nsilenciosa y segura con m\u00e1xima tracci\u00f3n en todo tipo de clima\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-742cff2c\" data-id=\"742cff2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39990bd9 elementor-widget elementor-widget-icon-box\" data-id=\"39990bd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNomenclatura LT\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVeh\u00edculos utilitarios o de carga, ofrece\nsilenciosa y segura con m\u00e1xima tracci\u00f3n en todo tipo de clima adicionalmente mayor rendimiento.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5915a671 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5915a671\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-21bd58d5\" data-id=\"21bd58d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6db42249 elementor-widget elementor-widget-text-editor\" data-id=\"6db42249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En ambos casos una m\u00e1xima rotaci\u00f3n por su dise\u00f1o de bloques en banda de rodamiento y costado con mayor huella de contacto. Aplica gama disponible con costado dual letras blancas y<a href=\"https:\/\/centrodono.com.sv\/\" target=\"_blank\"> negras<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55691c5e elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"55691c5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:71,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-33.jpg\" alt=\"OWL Disponible\" loading=\"lazy\" \/><figcaption class=\"elementor-image-carousel-caption\">OWL Disponible<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-35.jpg\" alt=\"Flotation Bloques de banda de rodadura m\u00e1s grandes y aumento del vac\u00edo\" loading=\"lazy\" \/><figcaption class=\"elementor-image-carousel-caption\">Flotation Bloques de banda de rodadura m\u00e1s grandes y aumento del vac\u00edo<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-37.jpg\" alt=\"LT-Metric Durabilidad robusta\" loading=\"lazy\" \/><figcaption class=\"elementor-image-carousel-caption\">LT-Metric Durabilidad robusta<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-39.jpg\" alt=\"P\/Euro-Metric Aumento de siping para Rendimiento h\u00famedo\" loading=\"lazy\" \/><figcaption class=\"elementor-image-carousel-caption\">P\/Euro-Metric Aumento de siping para Rendimiento h\u00famedo<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a72af80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a72af80\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-562b9111\" data-id=\"562b9111\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67a33ea5 elementor-widget elementor-widget-video\" data-id=\"67a33ea5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/open-country-at3.toyotireslatino.com\/wp-content\/uploads\/2021\/02\/Toyo-ATIII-V2-Final_HD-1080-1.mp4#t=1\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-723f3b9e elementor-widget elementor-widget-image\" data-id=\"723f3b9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-9-1024x678.jpg\" class=\"attachment-large size-large wp-image-10585\" alt=\"\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-9-1024x678.jpg 1024w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-9-300x199.jpg 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-9-768x508.jpg 768w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-9-600x397.jpg 600w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-9-64x42.jpg 64w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/OPAT3-Tarjetas-Informativas-LATAM-9.jpg 1360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"<p>\u00cdndice de Velocidad \u00cdndice de Carga T 116 &nbsp;<\/p>\n","protected":false},"featured_media":17971,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2308,2415,2409,2412,1881,1997,2463,2407],"product_tag":[2465,2464],"class_list":{"0":"post-10458","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-265-65r17","7":"product_cat-pick-up","8":"product_cat-pick-upcamioneta","9":"product_cat-suv","10":"product_cat-toyo","11":"product_cat-medida","12":"product_cat-opat3","13":"product_cat-tipo-vehiculo","14":"product_tag-opat3","15":"product_tag-open-country-a-t-iii","17":"first","18":"outofstock","19":"sale","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Toyo 265\/65 R17 OPAT3 6PR 116T - Centro de Servicio Do\u00f1o<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Toyo 265\/65 R17 OPAT3 6PR 116T - Centro de Servicio Do\u00f1o\" \/>\r\n<meta property=\"og:description\" content=\"\u00cdndice de Velocidad \u00cdndice de Carga T 116 &nbsp;\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Centro de Servicio Do\u00f1o\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-04-14T05:33:00+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2023\/09\/TOYO-OPAT3.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/\",\"url\":\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/\",\"name\":\"Toyo 265\/65 R17 OPAT3 6PR 116T - Centro de Servicio Do\u00f1o\",\"isPartOf\":{\"@id\":\"https:\/\/elsalvadorllantas.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2023\/09\/TOYO-OPAT3.jpg\",\"datePublished\":\"2021-12-15T17:33:13+00:00\",\"dateModified\":\"2026-04-14T05:33:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#primaryimage\",\"url\":\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2023\/09\/TOYO-OPAT3.jpg\",\"contentUrl\":\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2023\/09\/TOYO-OPAT3.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/elsalvadorllantas.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda en linea\",\"item\":\"https:\/\/elsalvadorllantas.com\/index.php\/tienda-en-linea\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toyo 265\/65 R17 OPAT3 6PR 116T\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elsalvadorllantas.com\/#website\",\"url\":\"https:\/\/elsalvadorllantas.com\/\",\"name\":\"Centro de Servicio Do\u00f1o\",\"description\":\"Venta de Llantas Nuevas - \u00a1Cotiza Ya!\",\"publisher\":{\"@id\":\"https:\/\/elsalvadorllantas.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elsalvadorllantas.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elsalvadorllantas.com\/#organization\",\"name\":\"Centro de Servicio Do\u00f1o\",\"url\":\"https:\/\/elsalvadorllantas.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elsalvadorllantas.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Logo_Don\u0303o_Editable-CMYK-2.png\",\"contentUrl\":\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Logo_Don\u0303o_Editable-CMYK-2.png\",\"width\":2139,\"height\":779,\"caption\":\"Centro de Servicio Do\u00f1o\"},\"image\":{\"@id\":\"https:\/\/elsalvadorllantas.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toyo 265\/65 R17 OPAT3 6PR 116T - Centro de Servicio Do\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/","og_locale":"es_ES","og_type":"article","og_title":"Toyo 265\/65 R17 OPAT3 6PR 116T - Centro de Servicio Do\u00f1o","og_description":"\u00cdndice de Velocidad \u00cdndice de Carga T 116 &nbsp;","og_url":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/","og_site_name":"Centro de Servicio Do\u00f1o","article_modified_time":"2026-04-14T05:33:00+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2023\/09\/TOYO-OPAT3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/","url":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/","name":"Toyo 265\/65 R17 OPAT3 6PR 116T - Centro de Servicio Do\u00f1o","isPartOf":{"@id":"https:\/\/elsalvadorllantas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#primaryimage"},"image":{"@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#primaryimage"},"thumbnailUrl":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2023\/09\/TOYO-OPAT3.jpg","datePublished":"2021-12-15T17:33:13+00:00","dateModified":"2026-04-14T05:33:00+00:00","breadcrumb":{"@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#primaryimage","url":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2023\/09\/TOYO-OPAT3.jpg","contentUrl":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2023\/09\/TOYO-OPAT3.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/toyo-265-65-r17-opat3-6pr-116t\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/elsalvadorllantas.com\/"},{"@type":"ListItem","position":2,"name":"Tienda en linea","item":"https:\/\/elsalvadorllantas.com\/index.php\/tienda-en-linea\/"},{"@type":"ListItem","position":3,"name":"Toyo 265\/65 R17 OPAT3 6PR 116T"}]},{"@type":"WebSite","@id":"https:\/\/elsalvadorllantas.com\/#website","url":"https:\/\/elsalvadorllantas.com\/","name":"Centro de Servicio Do\u00f1o","description":"Venta de Llantas Nuevas - \u00a1Cotiza Ya!","publisher":{"@id":"https:\/\/elsalvadorllantas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elsalvadorllantas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elsalvadorllantas.com\/#organization","name":"Centro de Servicio Do\u00f1o","url":"https:\/\/elsalvadorllantas.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elsalvadorllantas.com\/#\/schema\/logo\/image\/","url":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Logo_Don\u0303o_Editable-CMYK-2.png","contentUrl":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Logo_Don\u0303o_Editable-CMYK-2.png","width":2139,"height":779,"caption":"Centro de Servicio Do\u00f1o"},"image":{"@id":"https:\/\/elsalvadorllantas.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product\/10458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product\/10458\/revisions"}],"predecessor-version":[{"id":20492,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product\/10458\/revisions\/20492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/media\/17971"}],"wp:attachment":[{"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/media?parent=10458"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=10458"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=10458"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=10458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}