{"id":8188,"date":"2021-08-24T23:07:41","date_gmt":"2021-08-24T23:07:41","guid":{"rendered":"https:\/\/elsalvadorllantas.com\/index.php\/product\/maxxis-255-55-r18-s-pro\/"},"modified":"2026-04-13T23:27:31","modified_gmt":"2026-04-14T05:27:31","slug":"maxxis-255-55-r18-s-pro","status":"publish","type":"product","link":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/","title":{"rendered":"Maxxis 255\/55 R18 S-PRO"},"content":{"rendered":"<table style=\"height: 67px;\" border=\"2\" width=\"777\">\n<tbody>\n<tr style=\"text-align: center;\">\n<td>Lonaje<\/td>\n<td>Indice de Carga<\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td><\/td>\n<td>109W<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Modelo<\/strong><br \/>\nEl modelo asim\u00e9trico del neum\u00e1tico SPRO proporciona un manejo optimo, una respuesta<br \/>\ndeportiva una conducci\u00f3n c\u00f3moda.<\/p>\n<p><strong>Generalidades.<\/strong><br \/>\nMejor agarre y estabilidad a altas velocidades con bajos niveles de ruido para una conducci\u00f3n c\u00f3moda<br \/>\nel dise\u00f1o reforzado del hombro proporciona un excelente agarre en las curvas<br \/>\nel dise\u00f1o de perfil crea un \u00e1rea de contacto uniforme, lo que prolonga la vida \u00fatil de los neum\u00e1ticos.<\/p>\n<p><strong>Beneficios.<\/strong><\/p>\n<ul>\n<li>Larga vida \u00fatil de la llanta con buen millaje.<\/li>\n<li>Buen funcionamiento en condiciones de lluvia.<\/li>\n<li>Dise\u00f1o de agilidad y capacidad de conducci\u00f3n.<\/li>\n<li>Estabilidad y confort<\/li>\n<li>Paseos quietos y tranquilos.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-9200\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/KAPSEN-RS21-llantas-2-300x300.png\" alt=\"\" width=\"182\" height=\"182\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/KAPSEN-RS21-llantas-2-300x300.png 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/KAPSEN-RS21-llantas-2-150x150.png 150w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/KAPSEN-RS21-llantas-2-350x350.png 350w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/KAPSEN-RS21-llantas-2-100x100.png 100w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/KAPSEN-RS21-llantas-2-64x64.png 64w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/KAPSEN-RS21-llantas-2.png 404w\" sizes=\"(max-width: 182px) 100vw, 182px\" loading=\"lazy\" \/> <img decoding=\"async\" class=\"alignnone wp-image-9201\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-1-124x300.png\" alt=\"\" width=\"70\" height=\"169\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-1-124x300.png 124w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-1-64x155.png 64w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-1.png 162w\" sizes=\"(max-width: 70px) 100vw, 70px\" loading=\"lazy\" \/> <img decoding=\"async\" class=\"alignnone wp-image-9202\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-3-231x300.png\" alt=\"\" width=\"134\" height=\"173\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-3-231x300.png 231w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-3-64x83.png 64w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-3.png 302w\" sizes=\"(max-width: 134px) 100vw, 134px\" loading=\"lazy\" \/><\/p>\n<p><strong>Caracter\u00edsticas de desempe\u00f1o<\/strong><\/p>\n<ul>\n<li>Ahorro de combustible.<\/li>\n<li>Estabilidad y confort<\/li>\n<li>Maniobrabilidad en ambientes h\u00famedos<\/li>\n<\/ul>\n<p><strong>Caracter\u00edsticas y beneficios de la construcci\u00f3n<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9203\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-4-300x143.png\" alt=\"\" width=\"300\" height=\"143\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-4-300x143.png 300w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-4-64x31.png 64w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-4.png 577w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9204\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-5.png\" alt=\"\" width=\"110\" height=\"162\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-5.png 183w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-5-64x94.png 64w\" sizes=\"(max-width: 110px) 100vw, 110px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9205\" src=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-6.png\" alt=\"\" width=\"155\" height=\"159\" srcset=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-6.png 275w, https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/S-PRO-MAXXIS-6-64x66.png 64w\" sizes=\"(max-width: 155px) 100vw, 155px\" \/><\/p>\n<ul>\n<li>Excelente funcionamiento en epoca de verano.<\/li>\n<li>El patr\u00f3n hace que su ruido en cabina sea el menor posible.<\/li>\n<li>El componente de s\u00edlice proporciona una mayor durabilidad y proporciona un mayor millaje.<\/li>\n<li>Cuatro ranuras circunferenciales proporcionan una excelente dispersi\u00f3n de agua.<\/li>\n<li>Excelente manejo y estabilidad.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lonaje Indice de Carga 109W Modelo El modelo asim\u00e9trico del neum\u00e1tico SPRO proporciona un manejo optimo, una respuesta deportiva una conducci\u00f3n c\u00f3moda. Generalidades. Mejor agarre y estabilidad a altas velocidades con bajos niveles de ruido para una conducci\u00f3n c\u00f3moda el dise\u00f1o reforzado del hombro proporciona un excelente agarre en las curvas el dise\u00f1o de perfil<br \/><a class=\"more-link\" href=\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/\"><br \/>\n        Ver m\u00e1s<span class=\"screen-reader-text\"> \u00abMaxxis 255\/55 R18 S-PRO\u00bb<\/span><\/a><\/p>\n","protected":false},"featured_media":17956,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2252,1880,1899,2412,2407],"product_tag":[],"class_list":["post-8188","product","type-product","status-publish","has-post-thumbnail","product_cat-255-55r18","product_cat-maxxis","product_cat-s-pro","product_cat-suv","product_cat-tipo-vehiculo","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Maxxis 255\/55 R18 S-PRO - Centro de Servicio Do\u00f1o<\/title>\r\n<meta name=\"description\" content=\"El modelo asim\u00e9trico del neum\u00e1tico SPRO proporciona un manejo optimo, una respuestadeportiva una conducci\u00f3n c\u00f3moda.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Maxxis 255\/55 R18 S-PRO - Centro de Servicio Do\u00f1o\" \/>\r\n<meta property=\"og:description\" content=\"El modelo asim\u00e9trico del neum\u00e1tico SPRO proporciona un manejo optimo, una respuestadeportiva una conducci\u00f3n c\u00f3moda.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Centro de Servicio Do\u00f1o\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-04-14T05:27:31+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/LLANTAS-MAXXIS-S-PRO.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/producto\\\/maxxis-255-55-r18-s-pro\\\/\",\"url\":\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/producto\\\/maxxis-255-55-r18-s-pro\\\/\",\"name\":\"Maxxis 255\\\/55 R18 S-PRO - Centro de Servicio Do\u00f1o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/producto\\\/maxxis-255-55-r18-s-pro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/producto\\\/maxxis-255-55-r18-s-pro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elsalvadorllantas.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/LLANTAS-MAXXIS-S-PRO.jpg\",\"datePublished\":\"2021-08-24T23:07:41+00:00\",\"dateModified\":\"2026-04-14T05:27:31+00:00\",\"description\":\"El modelo asim\u00e9trico del neum\u00e1tico SPRO proporciona un manejo optimo, una respuestadeportiva una conducci\u00f3n c\u00f3moda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/producto\\\/maxxis-255-55-r18-s-pro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/producto\\\/maxxis-255-55-r18-s-pro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/producto\\\/maxxis-255-55-r18-s-pro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elsalvadorllantas.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/LLANTAS-MAXXIS-S-PRO.jpg\",\"contentUrl\":\"https:\\\/\\\/elsalvadorllantas.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/LLANTAS-MAXXIS-S-PRO.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/producto\\\/maxxis-255-55-r18-s-pro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/elsalvadorllantas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda en linea\",\"item\":\"https:\\\/\\\/elsalvadorllantas.com\\\/index.php\\\/tienda-en-linea\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maxxis 255\\\/55 R18 S-PRO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/#website\",\"url\":\"https:\\\/\\\/elsalvadorllantas.com\\\/\",\"name\":\"Centro de Servicio Do\u00f1o\",\"description\":\"Venta de Llantas Nuevas - \u00a1Cotiza Ya!\",\"publisher\":{\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elsalvadorllantas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/#organization\",\"name\":\"Centro de Servicio Do\u00f1o\",\"url\":\"https:\\\/\\\/elsalvadorllantas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elsalvadorllantas.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Logo_Don\u0303o_Editable-CMYK-2.png\",\"contentUrl\":\"https:\\\/\\\/elsalvadorllantas.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Logo_Don\u0303o_Editable-CMYK-2.png\",\"width\":2139,\"height\":779,\"caption\":\"Centro de Servicio Do\u00f1o\"},\"image\":{\"@id\":\"https:\\\/\\\/elsalvadorllantas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maxxis 255\/55 R18 S-PRO - Centro de Servicio Do\u00f1o","description":"El modelo asim\u00e9trico del neum\u00e1tico SPRO proporciona un manejo optimo, una respuestadeportiva una conducci\u00f3n c\u00f3moda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/","og_locale":"es_ES","og_type":"article","og_title":"Maxxis 255\/55 R18 S-PRO - Centro de Servicio Do\u00f1o","og_description":"El modelo asim\u00e9trico del neum\u00e1tico SPRO proporciona un manejo optimo, una respuestadeportiva una conducci\u00f3n c\u00f3moda.","og_url":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/","og_site_name":"Centro de Servicio Do\u00f1o","article_modified_time":"2026-04-14T05:27:31+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/LLANTAS-MAXXIS-S-PRO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/","url":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/","name":"Maxxis 255\/55 R18 S-PRO - Centro de Servicio Do\u00f1o","isPartOf":{"@id":"https:\/\/elsalvadorllantas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/#primaryimage"},"image":{"@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/#primaryimage"},"thumbnailUrl":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/LLANTAS-MAXXIS-S-PRO.jpg","datePublished":"2021-08-24T23:07:41+00:00","dateModified":"2026-04-14T05:27:31+00:00","description":"El modelo asim\u00e9trico del neum\u00e1tico SPRO proporciona un manejo optimo, una respuestadeportiva una conducci\u00f3n c\u00f3moda.","breadcrumb":{"@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/#primaryimage","url":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/LLANTAS-MAXXIS-S-PRO.jpg","contentUrl":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/08\/LLANTAS-MAXXIS-S-PRO.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/elsalvadorllantas.com\/index.php\/producto\/maxxis-255-55-r18-s-pro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/elsalvadorllantas.com\/"},{"@type":"ListItem","position":2,"name":"Tienda en linea","item":"https:\/\/elsalvadorllantas.com\/index.php\/tienda-en-linea\/"},{"@type":"ListItem","position":3,"name":"Maxxis 255\/55 R18 S-PRO"}]},{"@type":"WebSite","@id":"https:\/\/elsalvadorllantas.com\/#website","url":"https:\/\/elsalvadorllantas.com\/","name":"Centro de Servicio Do\u00f1o","description":"Venta de Llantas Nuevas - \u00a1Cotiza Ya!","publisher":{"@id":"https:\/\/elsalvadorllantas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elsalvadorllantas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elsalvadorllantas.com\/#organization","name":"Centro de Servicio Do\u00f1o","url":"https:\/\/elsalvadorllantas.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elsalvadorllantas.com\/#\/schema\/logo\/image\/","url":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Logo_Don\u0303o_Editable-CMYK-2.png","contentUrl":"https:\/\/elsalvadorllantas.com\/wp-content\/uploads\/2021\/12\/Logo_Don\u0303o_Editable-CMYK-2.png","width":2139,"height":779,"caption":"Centro de Servicio Do\u00f1o"},"image":{"@id":"https:\/\/elsalvadorllantas.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product\/8188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product\/8188\/revisions"}],"predecessor-version":[{"id":20701,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product\/8188\/revisions\/20701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/media\/17956"}],"wp:attachment":[{"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/media?parent=8188"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=8188"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=8188"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elsalvadorllantas.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=8188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}